{"id":6027,"date":"2020-04-13T09:13:24","date_gmt":"2020-04-13T13:13:24","guid":{"rendered":"http:\/\/demosite2.asurtec.com\/oc-covid19-responses-services\/"},"modified":"2020-04-13T09:22:09","modified_gmt":"2020-04-13T13:22:09","slug":"reponses-oc-covid19","status":"publish","type":"post","link":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/","title":{"rendered":"R\u00e9ponses d&#8217;Orchestres Canada \u00e0 la COVID-19"},"content":{"rendered":"<p style=\"text-align: right;\"><em>Une lettre de notre directrice g\u00e9n\u00e9rale, Katherine Carleton<\/em><\/p>\n<p>Chers membres,<\/p>\n<p>Depuis quatre semaines, une vague d\u2019annulations d\u00e9ferle sur le pays dans la foul\u00e9e des mesures de confinement visant \u00e0 limiter la propagation de la COVID-19. Chacun de nos quelque 130 orchestres membres a \u00e9t\u00e9 touch\u00e9.<\/p>\n<p>Les orchestres canadiens ont fait preuve d\u2019une adaptabilit\u00e9 inspirante en cr\u00e9ant plus de contenu en ligne que jamais. Orchestres Canada a aussi augment\u00e9 son activit\u00e9 en ligne pour appuyer ses membres durant cette p\u00e9riode de d\u00e9fis sans pr\u00e9c\u00e9dent. Convaincus que les orchestres sont plus forts ensemble qu\u2019ils ne le sont isol\u00e9ment, nous avons \u00e9largi et adapt\u00e9 les quatre piliers de notre mission pour les aider \u00e0 faire face \u00e0 la crise actuelle.<\/p>\n<h3>Convocation<\/h3>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright size-medium wp-image-5988\" src=\"https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Meeting-with-computers-300x188.jpg\" alt=\"\" width=\"300\" height=\"188\" srcset=\"https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Meeting-with-computers-300x188.jpg 300w, https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Meeting-with-computers.jpg 433w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/>Au cours du dernier mois, OC a convoqu\u00e9 des r\u00e9unions en ligne avec des groupes intervenants pour \u00e9changer des renseignements et des id\u00e9es, ainsi que pour concevoir des r\u00e9actions collectives \u00e0 la fermeture actuelle. Nous avons tenu des r\u00e9unions avec les chefs de la direction des orchestres, les dirigeants d\u2019orchestres de jeunes, les gestionnaires du personnel, de m\u00eame que les responsables du marketing et de l\u2019\u00e9ducation. Nous pr\u00e9voyons poursuivre et \u00e9largir ces rencontres. Dites-nous ce dont vous avez besoin.<\/p>\n<h3>D\u00e9fense des int\u00e9r\u00eats<\/h3>\n<p><img decoding=\"async\" class=\"alignright size-medium wp-image-5990\" src=\"https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Writing-a-letter-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Writing-a-letter-300x187.jpg 300w, https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Writing-a-letter.jpg 433w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><\/p>\n<p>Notre comit\u00e9 de la d\u00e9fense des int\u00e9r\u00eats s\u2019est employ\u00e9 \u00e0 d\u00e9terminer la meilleure fa\u00e7on d\u2019aborder les d\u00e9cideurs f\u00e9d\u00e9raux et de les sensibiliser aux besoins des orchestres. Nous avons \u00e9crit <a href=\"https:\/\/oc.ca\/fr\/resource\/lettre-oc-ministres\/\">une lettre \u00e0 plusieurs ministres<\/a>, et nous encourageons nos membres \u00e0 la transmettre \u00e0 leurs d\u00e9put\u00e9s. Bien s\u00fbr, nous nous sommes concentr\u00e9s sur les mesures d\u2019urgence \u00e0 court terme. C\u2019est ce que nous continuerons \u00e0 faire tout en vous consultant afin d\u2019\u00e9laborer des strat\u00e9gies de relance et de r\u00e9silience pour les orchestres canadiens.<\/p>\n<h3>Partage des connaissances<\/h3>\n<p>Nous envoyons \u00e0 nos membres de fr\u00e9quentes mises \u00e0 jour sur la situation touchant directement le secteur des arts, ainsi que des ressources et outils pour les aider \u00e0 faire face \u00e0 la r\u00e9alit\u00e9 actuelle. Nous sommes aussi ravis de faire conna\u00eetre vos initiatives et triomphes. Vous pouvez lire ces mises \u00e0 jour \u00e0 notre <a href=\"https:\/\/oc.ca\/fr\/covid-19\/\">page COVID-19<\/a> ou en vous <a href=\"https:\/\/oc.ca\/fr\/simpliquer\/abonnement-infolettre\/\">abonnant \u00e0 notre infolettre.<\/a><\/p>\n<h3>Recherche<\/h3>\n<p><img decoding=\"async\" class=\"alignright size-medium wp-image-5986\" src=\"https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Bookjs-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Bookjs-300x225.jpg 300w, https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Bookjs.jpg 433w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><\/p>\n<p>Jusqu\u2019\u00e0 maintenant, nous avons men\u00e9 deux sondages visant \u00e0 mesurer l\u2019impact imm\u00e9diat des fermetures dues \u00e0 la COVID-19 sur nos membres et nous avons communiqu\u00e9 certaines observations initiales de notre statisticien, Steve Smith. Cette collecte de donn\u00e9es est une d\u00e9marche constante; nous savons que vous avez \u00e9t\u00e9 sond\u00e9s, mais nous continuerons \u00e0 recueillir et analyser d\u2019autres donn\u00e9es.<\/p>\n<p>Je vous incite \u00e0 jeter un coup d\u2019\u0153il \u00e0 l\u2019\u00e9tat de nos activit\u00e9s et vous encourage \u00e0 communiquer avec nous pour partager des ressources, brasser des id\u00e9es ou simplement v\u00e9rifier l\u2019\u00e9tat des choses. Prenez bien soin de vous.<\/p>\n<p>Katherine Carleton<br \/>\nDirectrice g\u00e9n\u00e9rale<br \/>\nOrchestras Canada\/Orchestres Canada<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une lettre de notre directrice g\u00e9n\u00e9rale, Katherine Carleton Chers membres, Depuis quatre semaines, une vague d\u2019annulations d\u00e9ferle sur le pays dans la foul\u00e9e des mesures de confinement visant \u00e0 limiter la propagation de la COVID-19. Chacun de nos quelque 130 orchestres membres a \u00e9t\u00e9 touch\u00e9. Les orchestres canadiens ont fait preuve d\u2019une adaptabilit\u00e9 inspirante en [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[231],"tags":[488,522,520,523,498,521,524,341],"class_list":["post-6027","post","type-post","status-publish","format-standard","hentry","category-blogue","tag-advocacy","tag-advocacy-fr","tag-convening","tag-convening-fr","tag-covid-19","tag-knowledge-sharing","tag-knowledge-sharing-fr","tag-recherche"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9ponses d&#039;Orchestres Canada \u00e0 la COVID-19 - Orchestras Canada\/Orchestres Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9ponses d&#039;Orchestres Canada \u00e0 la COVID-19 - Orchestras Canada\/Orchestres Canada\" \/>\n<meta property=\"og:description\" content=\"Une lettre de notre directrice g\u00e9n\u00e9rale, Katherine Carleton Chers membres, Depuis quatre semaines, une vague d\u2019annulations d\u00e9ferle sur le pays dans la foul\u00e9e des mesures de confinement visant \u00e0 limiter la propagation de la COVID-19. Chacun de nos quelque 130 orchestres membres a \u00e9t\u00e9 touch\u00e9. Les orchestres canadiens ont fait preuve d\u2019une adaptabilit\u00e9 inspirante en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/\" \/>\n<meta property=\"og:site_name\" content=\"Orchestras Canada\/Orchestres Canada\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-13T13:13:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-13T13:22:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Meeting-with-computers-300x188.jpg\" \/>\n<meta name=\"author\" content=\"Boran Zaza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Boran Zaza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/reponses-oc-covid19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/reponses-oc-covid19\\\/\"},\"author\":{\"name\":\"Boran Zaza\",\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#\\\/schema\\\/person\\\/7796a50335e35c17d46b21fce90bda6a\"},\"headline\":\"R\u00e9ponses d&#8217;Orchestres Canada \u00e0 la COVID-19\",\"datePublished\":\"2020-04-13T13:13:24+00:00\",\"dateModified\":\"2020-04-13T13:22:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/reponses-oc-covid19\\\/\"},\"wordCount\":497,\"publisher\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/reponses-oc-covid19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oc.ca\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Meeting-with-computers-300x188.jpg\",\"keywords\":[\"Advocacy\",\"Advocacy\",\"Convening\",\"Convening\",\"COVID-19\",\"Knowledge-sharing\",\"Knowledge-sharing\",\"Recherche\"],\"articleSection\":[\"Blogue\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/reponses-oc-covid19\\\/\",\"url\":\"https:\\\/\\\/oc.ca\\\/fr\\\/reponses-oc-covid19\\\/\",\"name\":\"R\u00e9ponses d'Orchestres Canada \u00e0 la COVID-19 - Orchestras Canada\\\/Orchestres Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/reponses-oc-covid19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/reponses-oc-covid19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oc.ca\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Meeting-with-computers-300x188.jpg\",\"datePublished\":\"2020-04-13T13:13:24+00:00\",\"dateModified\":\"2020-04-13T13:22:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/reponses-oc-covid19\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oc.ca\\\/fr\\\/reponses-oc-covid19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/reponses-oc-covid19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/oc.ca\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Meeting-with-computers-300x188.jpg\",\"contentUrl\":\"https:\\\/\\\/oc.ca\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Meeting-with-computers-300x188.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/reponses-oc-covid19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/oc.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9ponses d&#8217;Orchestres Canada \u00e0 la COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/oc.ca\\\/en\\\/\",\"name\":\"Orchestras Canada\\\/Orchestres Canada\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oc.ca\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#organization\",\"name\":\"Orchestras Canada\\\/Orchestres Canada\",\"url\":\"https:\\\/\\\/oc.ca\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oc.ca\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/cropped-OC-Logo-800x200-1.png\",\"contentUrl\":\"https:\\\/\\\/oc.ca\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/cropped-OC-Logo-800x200-1.png\",\"width\":400,\"height\":100,\"caption\":\"Orchestras Canada\\\/Orchestres Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#\\\/schema\\\/person\\\/7796a50335e35c17d46b21fce90bda6a\",\"name\":\"Boran Zaza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56b5fa935f2a6deb56743eedfecce8f25a520084588141457887d2c9648c9c08?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56b5fa935f2a6deb56743eedfecce8f25a520084588141457887d2c9648c9c08?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56b5fa935f2a6deb56743eedfecce8f25a520084588141457887d2c9648c9c08?s=96&d=mm&r=g\",\"caption\":\"Boran Zaza\"},\"url\":\"https:\\\/\\\/oc.ca\\\/fr\\\/author\\\/boranzaza\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9ponses d'Orchestres Canada \u00e0 la COVID-19 - Orchestras Canada\/Orchestres Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9ponses d'Orchestres Canada \u00e0 la COVID-19 - Orchestras Canada\/Orchestres Canada","og_description":"Une lettre de notre directrice g\u00e9n\u00e9rale, Katherine Carleton Chers membres, Depuis quatre semaines, une vague d\u2019annulations d\u00e9ferle sur le pays dans la foul\u00e9e des mesures de confinement visant \u00e0 limiter la propagation de la COVID-19. Chacun de nos quelque 130 orchestres membres a \u00e9t\u00e9 touch\u00e9. Les orchestres canadiens ont fait preuve d\u2019une adaptabilit\u00e9 inspirante en [&hellip;]","og_url":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/","og_site_name":"Orchestras Canada\/Orchestres Canada","article_published_time":"2020-04-13T13:13:24+00:00","article_modified_time":"2020-04-13T13:22:09+00:00","og_image":[{"url":"https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Meeting-with-computers-300x188.jpg","type":"","width":"","height":""}],"author":"Boran Zaza","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Boran Zaza","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/#article","isPartOf":{"@id":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/"},"author":{"name":"Boran Zaza","@id":"https:\/\/oc.ca\/en\/#\/schema\/person\/7796a50335e35c17d46b21fce90bda6a"},"headline":"R\u00e9ponses d&#8217;Orchestres Canada \u00e0 la COVID-19","datePublished":"2020-04-13T13:13:24+00:00","dateModified":"2020-04-13T13:22:09+00:00","mainEntityOfPage":{"@id":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/"},"wordCount":497,"publisher":{"@id":"https:\/\/oc.ca\/en\/#organization"},"image":{"@id":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/#primaryimage"},"thumbnailUrl":"https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Meeting-with-computers-300x188.jpg","keywords":["Advocacy","Advocacy","Convening","Convening","COVID-19","Knowledge-sharing","Knowledge-sharing","Recherche"],"articleSection":["Blogue"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/","url":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/","name":"R\u00e9ponses d'Orchestres Canada \u00e0 la COVID-19 - Orchestras Canada\/Orchestres Canada","isPartOf":{"@id":"https:\/\/oc.ca\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/#primaryimage"},"image":{"@id":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/#primaryimage"},"thumbnailUrl":"https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Meeting-with-computers-300x188.jpg","datePublished":"2020-04-13T13:13:24+00:00","dateModified":"2020-04-13T13:22:09+00:00","breadcrumb":{"@id":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oc.ca\/fr\/reponses-oc-covid19\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/#primaryimage","url":"https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Meeting-with-computers-300x188.jpg","contentUrl":"https:\/\/oc.ca\/wp-content\/uploads\/2020\/04\/Meeting-with-computers-300x188.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/oc.ca\/fr\/reponses-oc-covid19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oc.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9ponses d&#8217;Orchestres Canada \u00e0 la COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/oc.ca\/en\/#website","url":"https:\/\/oc.ca\/en\/","name":"Orchestras Canada\/Orchestres Canada","description":"","publisher":{"@id":"https:\/\/oc.ca\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oc.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/oc.ca\/en\/#organization","name":"Orchestras Canada\/Orchestres Canada","url":"https:\/\/oc.ca\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/oc.ca\/en\/#\/schema\/logo\/image\/","url":"https:\/\/oc.ca\/wp-content\/uploads\/2019\/03\/cropped-OC-Logo-800x200-1.png","contentUrl":"https:\/\/oc.ca\/wp-content\/uploads\/2019\/03\/cropped-OC-Logo-800x200-1.png","width":400,"height":100,"caption":"Orchestras Canada\/Orchestres Canada"},"image":{"@id":"https:\/\/oc.ca\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/oc.ca\/en\/#\/schema\/person\/7796a50335e35c17d46b21fce90bda6a","name":"Boran Zaza","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/56b5fa935f2a6deb56743eedfecce8f25a520084588141457887d2c9648c9c08?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56b5fa935f2a6deb56743eedfecce8f25a520084588141457887d2c9648c9c08?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56b5fa935f2a6deb56743eedfecce8f25a520084588141457887d2c9648c9c08?s=96&d=mm&r=g","caption":"Boran Zaza"},"url":"https:\/\/oc.ca\/fr\/author\/boranzaza\/"}]}},"_links":{"self":[{"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/posts\/6027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/comments?post=6027"}],"version-history":[{"count":2,"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/posts\/6027\/revisions"}],"predecessor-version":[{"id":6028,"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/posts\/6027\/revisions\/6028"}],"wp:attachment":[{"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/media?parent=6027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/categories?post=6027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/tags?post=6027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}