{"id":13645,"date":"2024-06-21T17:36:46","date_gmt":"2024-06-21T21:36:46","guid":{"rendered":"http:\/\/demosite2.asurtec.com\/?p=13645"},"modified":"2024-06-21T20:28:54","modified_gmt":"2024-06-22T00:28:54","slug":"developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext","status":"publish","type":"post","link":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/","title":{"rendered":"D\u00e9veloppement environnemental durable dans les orchestres : Ce que j&#8217;ai appris \u00e0 Classical:NEXT"},"content":{"rendered":"<p><img decoding=\"async\" class=\" wp-image-11326 alignleft\" src=\"https:\/\/oc.ca\/wp-content\/uploads\/2022\/12\/2022_11_01_Boran_Headshots_227OC.png\" alt=\"Headshot of Boran Zaza\" width=\"82\" height=\"82\" srcset=\"https:\/\/oc.ca\/wp-content\/uploads\/2022\/12\/2022_11_01_Boran_Headshots_227OC.png 600w, https:\/\/oc.ca\/wp-content\/uploads\/2022\/12\/2022_11_01_Boran_Headshots_227OC-300x300.png 300w, https:\/\/oc.ca\/wp-content\/uploads\/2022\/12\/2022_11_01_Boran_Headshots_227OC-150x150.png 150w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><\/p>\n<p>Par <a href=\"https:\/\/oc.ca\/fr\/bios\/boran-zaza\/\">Boran Zaza<\/a>, directrice des communications et du d\u00e9veloppement d&#8217;Orchestres Canada<\/p>\n<hr \/>\n<p>Du 13 au 17 mai 2024, j&#8217;ai assist\u00e9 \u00e0 <a href=\"https:\/\/classicalnext.com\/\">Classical:NEXT<\/a> \u00e0 Berlin, en Allemagne. Voici la deuxi\u00e8me partie d&#8217;une s\u00e9rie de trois articles de blog intitul\u00e9s \u00ab Ce que j&#8217;ai appris \u00e0 Classical:NEXT. \u00bb<br \/>\nVous pouvez lire la premi\u00e8re partie ici : <a href=\"https:\/\/oc.ca\/fr\/modeles-de-leadership-novateurs-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/\">Mod\u00e8les de leadership novateurs dans les orchestres <\/a><\/p>\n<hr \/>\n<h3><b><span data-contrast=\"auto\">Petits changements : Un grand impact<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/h3>\n<p>Je ne sais plus qui a dit cela, mais cela m&#8217;a beaucoup impressionn\u00e9 : \u00ab La durabilit\u00e9 environnementale, ce n&#8217;est pas 2 % de la population qui changent compl\u00e8tement leur mode de vie, c&#8217;est 85 % de la population qui fait quelques changements. C&#8217;est ce qui aura le plus d&#8217;impact. \u00bb<\/p>\n<figure id=\"attachment_13625\" aria-describedby=\"caption-attachment-13625\" style=\"width: 307px\" class=\"wp-caption alignright\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-13625\" src=\"https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/IMG_7721-492x800.jpg\" alt=\"\" width=\"307\" height=\"499\" srcset=\"https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/IMG_7721-492x800.jpg 492w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/IMG_7721-185x300.jpg 185w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/IMG_7721-768x1248.jpg 768w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/IMG_7721-945x1536.jpg 945w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/IMG_7721-1260x2048.jpg 1260w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/IMG_7721-scaled.jpg 1289w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><figcaption id=\"caption-attachment-13625\" class=\"wp-caption-text\">Lea Br\u00fcckner lors de sa pr\u00e9sentation \u00e0 C:N | Photo : Boran Zaza<\/figcaption><\/figure>\n<p>Lors de Classical:NEXT (C:N), j&#8217;ai eu le plaisir de rencontrer Lea Br\u00fcckner, violoniste, ambassadrice du climat et <a href=\"https:\/\/www.instagram.com\/lea.violin\/\">influenceuse Instagram<\/a> (non, elle n&#8217;a aucun lien de parent\u00e9 avec le compositeur, mais sachez que le compositeur Gabriel Prokofiev, petit-fils de Sergue\u00ef Prokofiev, \u00e9tait pr\u00e9sent \u00e0 C:N!). Lea \u00e9tait l&#8217;une des pr\u00e9sentatrices d&#8217;une session du congr\u00e8s intitul\u00e9e <em><strong>Positive Impact Through Sustainable Concerts<\/strong><\/em>, avec <strong>Beat Fehlmann<\/strong>, directeur artistique de la Deutsche Staatsphilharmonie Rheinland-Pfalz, et <strong>Asbj\u00f8rn Keiding<\/strong>, directeur de Danske Ensembler, Orkestre og Operainstitutioner (DEOO). Par souci de transparence, Beat et Asbj\u00f8rn ont eu l&#8217;initiative de partager la d\u00e9cision qu&#8217;ils ont prise en mati\u00e8re de transport pour se rendre de leur ville d&#8217;origine \u00e0 Berlin afin de participer \u00e0 C:N, et <strong>c&#8217;est ce qui m&#8217;a incit\u00e9 \u00e0 partager \u00e9galement la mienne<\/strong> \u00e0 la fin de ce billet de blog.<\/p>\n<h3><em>Green Monday<\/em>, et les publics soucieux de l&#8217;environnement<\/h3>\n<p>Au cours de l&#8217;ann\u00e9e \u00e9coul\u00e9e, Lea a \u00e9t\u00e9 la mod\u00e9ratrice des tables rondes du <a href=\"https:\/\/www.tonhalle.de\/green-monday-uebersicht\"><em>Green Monday<\/em><\/a>, une s\u00e9rie de concerts de l&#8217;Orchestre symphonique de D\u00fcsseldorf pr\u00e9sent\u00e9e \u00e0 la Tonhalle de D\u00fcsseldorf et qui a remport\u00e9 un vif succ\u00e8s. L&#8217;orchestre a consacr\u00e9 12 concerts de sa saison, soit un par mois, \u00e0 l&#8217;exploration de la durabilit\u00e9 et a invit\u00e9 son public \u00e0 se joindre \u00e0 lui pour vivre une exp\u00e9rience de concert \u00e0 faibles \u00e9missions. \u00c0 chaque concert, un th\u00e8me environnemental a \u00e9t\u00e9 pr\u00e9sent\u00e9 dans le cadre d&#8217;une table ronde, l&#8217;id\u00e9e a \u00e9t\u00e9 test\u00e9e lors de ce concert et le public a vot\u00e9 pour savoir s&#8217;il souhaitait que cette initiative soit poursuivie ou non. Parmi les initiatives, citons : <strong>demander au public de se rendre au concert en v\u00e9lo ou en transports publics<\/strong> et <strong>ajouter des supports \u00e0 v\u00e9los<\/strong> \u00e0 l&#8217;ext\u00e9rieur de la salle, <strong>r\u00e9duire la chaleur de la salle de concert de 1,5 degr\u00e9<\/strong>, <strong>r\u00e9duire l&#8217;\u00e9clairage sur sc\u00e8ne<\/strong>, servir des plats<strong> v\u00e9g\u00e9tariens uniquement lors des r\u00e9ceptions<\/strong>, et bien d&#8217;autres encore!<\/p>\n<figure id=\"attachment_13634\" aria-describedby=\"caption-attachment-13634\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-13634 size-large\" src=\"https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/231212_3Fragenan_Duesseldorfer_Symphoniker-Tonhalle_Foto-Susanne_Diesner-800x533.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/231212_3Fragenan_Duesseldorfer_Symphoniker-Tonhalle_Foto-Susanne_Diesner-800x533.jpg 800w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/231212_3Fragenan_Duesseldorfer_Symphoniker-Tonhalle_Foto-Susanne_Diesner-300x200.jpg 300w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/231212_3Fragenan_Duesseldorfer_Symphoniker-Tonhalle_Foto-Susanne_Diesner-768x512.jpg 768w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/231212_3Fragenan_Duesseldorfer_Symphoniker-Tonhalle_Foto-Susanne_Diesner.jpg 1500w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><figcaption id=\"caption-attachment-13634\" class=\"wp-caption-text\">La salle de concert Tonhalle de D\u00fcsseldorf | Photo : Susanne Diesner<\/figcaption><\/figure>\n<p>Pour ajouter une touche musicale \u00e0 tout cela, un petit fragment musical a \u00e9t\u00e9 ins\u00e9r\u00e9 au d\u00e9but de chaque concert. Onze compositeurs du monde entier se sont lanc\u00e9s dans l&#8217;exp\u00e9rience de s&#8217;inspirer de mots-cl\u00e9s tels que <strong>recyclage<\/strong>, <strong>efficacit\u00e9 \u00e9nerg\u00e9tique<\/strong> ou <strong>num\u00e9risation<\/strong> et de les transformer en musique que l&#8217;orchestre symphonique de D\u00fcsseldorf a interpr\u00e9t\u00e9e \u00e0 chaque <em>Green Monday<\/em>. \u00c0 la fin de la saison, les onze micro-\u0153uvres ont \u00e9t\u00e9 rassembl\u00e9es en une grande \u00ab \u0153uvre verte \u00bb avec des transitions compos\u00e9es par John Psathas sous la direction d&#8217;Axel Kober. #Recyclage<\/p>\n<p>\u00ab La grande majorit\u00e9 du public a vot\u00e9 OUI \u00e0 100 % des initiatives propos\u00e9es! \u00bb m&#8217;a dit fi\u00e8rement L\u00e9a. Leur exp\u00e9rience m&#8217;a appris <strong>que le fait d&#8217;associer les spectateurs.trices \u00e0 la prise de d\u00e9cision les fait passer d&#8217;un r\u00f4le passif \u00e0 un r\u00f4le de partenaire, o\u00f9 ils ont le sentiment que leur voix est entendue et qu&#8217;elle compte<\/strong>, et que leurs choix peuvent avoir une incidence positive sur l&#8217;avenir de leur orchestre et de leur plan\u00e8te.<\/p>\n<p>Lecture compl\u00e9mentaire : entretien de Michael Becker, directeur artistique de la Tonhalle de D\u00fcsseldorf, \u00e0 propos de <em>Green Monday<\/em> : <a href=\"https:\/\/www.visitduesseldorf.de\/storys\/en\/2023\/12\/12\/tonhalle-duesseldorf\/\">https:\/\/www.visitduesseldorf.de\/storys\/en\/2023\/12\/12\/tonhalle-duesseldorf\/<\/a><\/p>\n<h3>Guide de l&#8217;Orchestre vert nordique<\/h3>\n<p><i><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13627 alignleft\" src=\"https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/nordic-green-orchestra-guide-566x800.jpg\" alt=\"\" width=\"368\" height=\"520\" srcset=\"https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/nordic-green-orchestra-guide-566x800.jpg 566w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/nordic-green-orchestra-guide-212x300.jpg 212w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/nordic-green-orchestra-guide-768x1086.jpg 768w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/nordic-green-orchestra-guide-1086x1536.jpg 1086w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/nordic-green-orchestra-guide-1448x2048.jpg 1448w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/nordic-green-orchestra-guide-scaled.jpg 1482w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/>Le principal facteur d&#8217;\u00e9missions dans le secteur des concerts n&#8217;est pas le d\u00e9placement des artistes, <strong>mais celui du public.<\/strong> Cependant, la solution ne peut pas \u00eatre de ne pas organiser de concerts!<br \/>\n<\/span><\/i><\/p>\n<p>Cette citation est tir\u00e9e de la description de la session <em><strong>Positive Impact Through Sustainable Concerts<\/strong><\/em>. En 2022, 36 orchestres et festivals nordiques se sont r\u00e9unis \u00e0 Reykjav\u00edk et ont sign\u00e9 <a href=\"https:\/\/drive.google.com\/file\/d\/1dIRo1iwD8E0xtB7q6VjCdHFJthFAYBkv\/view\">une d\u00e9claration d&#8217;intention<\/a> intitul\u00e9e \u00ab Un avenir avec une culture durable. \u00bb Un an plus tard, apr\u00e8s des discussions au sein de six groupes de travail, le <a href=\"https:\/\/www.koda.dk\/media\/225742\/nordic-green-orchestra-guide.pdf\">Guide de l&#8217;Orchestre vert nordique<\/a> a vu le jour.<\/p>\n<p>Asbj\u00f8rn Keiding, directeur de DEOO, estime que <strong>le guide n&#8217;est pas seulement un document de travail interne, mais qu&#8217;il doit \u00e9galement \u00eatre communiqu\u00e9 au public.<\/strong> Comme l&#8217;a d\u00e9clar\u00e9 Asbj\u00f8rn lors de sa pr\u00e9sentation, \u00ab les orchestres \u00e0 eux seuls n&#8217;ont pas les pires \u00e9missions de carbone, [leur] pouvoir est d&#8217;influencer les spectateurs.trices et les musicien.ne.s. C&#8217;est ainsi que l&#8217;on peut changer les choses. \u00bb<\/p>\n<p>Le guide contient 6 chapitres couvrant les th\u00e8mes suivants :<\/p>\n<ul>\n<li>Leadership et gestion<\/li>\n<li>Communication et engagement du public<\/li>\n<li>Transport du public<\/li>\n<li>Approvisionnement et acquisition<\/li>\n<li>Tourn\u00e9es et d\u00e9placements du personnel<\/li>\n<li>Mesure et \u00e9valuation<\/li>\n<\/ul>\n<p><span data-contrast=\"auto\">Vous pouvez t\u00e9l\u00e9charger et lire l&#8217;int\u00e9gralit\u00e9 du Guide de l&#8217;Orchestre vert nordique ici (en anglais) : <\/span><a href=\"https:\/\/www.koda.dk\/media\/225742\/nordic-green-orchestra-guide.pdf\">https:\/\/www.koda.dk\/media\/225742\/nordic-green-orchestra-guide.pdf<\/a><\/p>\n<p><em>Note : Orchestres Canada esp\u00e8re commander une \u00e9dition canadienne du Guide vert des orchestres en 2025, et nous avons fait une demande de financement pour le r\u00e9aliser. Nous vous en dirons plus d\u00e8s que nous aurons des nouvelles! <\/em><\/p>\n<h3>Choix personnels<\/h3>\n<p>J&#8217;habite \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Rimouski\">Rimouski<\/a>, une tr\u00e8s belle ville du Qu\u00e9bec, au Canada, qui n&#8217;a pas d&#8217;a\u00e9roport international commercial. Il n&#8217;y avait pas beaucoup de fa\u00e7ons \u00e9cologiques de voyager de Rimouski \u00e0 Berlin, en Allemagne, pour assister \u00e0 Classical:NEXT, alors voici ce que j&#8217;ai fait :<\/p>\n<p><strong>J&#8217;ai pris le train de Rimouski \u00e0 Montr\u00e9al<\/strong> et <strong>j&#8217;ai pay\u00e9 les frais de compensation carbone pour mon vol aller-retour entre Montr\u00e9al et Berlin<\/strong> (avec une escale \u00e0 Francfort car il n&#8217;y avait pas de vol direct pour Berlin). Lorsque j&#8217;ai fait ma valise, j&#8217;ai pris soin d&#8217;emporter ma fid\u00e8le <strong>bouteille d&#8217;eau r\u00e9utilisable<\/strong> et un <strong>contenant alimentaire en plastique r\u00e9utilisable<\/strong>. La bo\u00eete alimentaire s&#8217;est av\u00e9r\u00e9e tr\u00e8s utile \u00e0 plusieurs reprises. J&#8217;ai utilis\u00e9 exclusivement <strong>les transports en commun<\/strong> pendant mon s\u00e9jour \u00e0 Berlin, \u00e0 l&#8217;exception d&#8217;un soir o\u00f9 j&#8217;ai pris un taxi pour rentrer \u00e0 ma chambre d&#8217;h\u00f4tel apr\u00e8s un <span data-contrast=\"auto\"><a href=\"https:\/\/www.youtube.com\/watch?v=tfFe9hZJQuk\">Candlelight Concert<\/a><\/span> tard dans la nuit qui \u00e9tait pr\u00e9sent\u00e9 comme une vitrine hors-Classical:NEXT.<\/p>\n<h3>Petite histoire : Chandelles et tremblements de terre<\/h3>\n<p>Le concert comprenait une \u0153uvre intitul\u00e9e <strong><em>The Richter Scale<\/em><\/strong> du compositeur allemand Boris Bergmann, \u00e9crite pour un piano Spirio Steinway (l&#8217;un de ces pianos m\u00e9caniques, qui sont des pianos qui peuvent jouer eux-m\u00eames! Regardez <a href=\"https:\/\/youtu.be\/TfQj3vAI7sk?si=saj-1lzOjb6MeC6y\">cette vid\u00e9o<\/a> pour une d\u00e9monstration) et un pianiste : Ji Liu. <strong>Ce fut l&#8217;une des exp\u00e9riences musicales les plus \u00e9poustouflantes que j&#8217;aie jamais v\u00e9cues<\/strong> : L&#8217;\u0153uvre imitait un tremblement de terre avec des degr\u00e9s croissants sur l&#8217;\u00e9chelle de Richter. Alors que nous approchions de la fin, le piano jouait un passage extr\u00eamement difficile, et le pianiste \u00e9tait presque en duel musical avec lui, en train de le combattre. C&#8217;\u00e9tait une exp\u00e9rience tr\u00e8s \u00e9mouvante, car je me souvenais de tous mes ami.e.s et de mes membres de famille qui avaient \u00e9t\u00e9 touch\u00e9s par le grand <a href=\"https:\/\/www.croixrouge.ca\/nos-champs-d-action\/interventions-en-cours\/interventions-anterieures\/seisme-en-turkiye-et-en-syrie\">tremblement de terre en Syrie, en Turquie et au Liban<\/a> l&#8217;ann\u00e9e derni\u00e8re. Le concert a eu lieu tard dans la nuit, dans une \u00e9glise remplie de bougies, et le m\u00e9lange de cette atmosph\u00e8re et de l&#8217;\u0153uvre musicale innovante \u00e9tait tr\u00e8s attrayant et rafra\u00eechissant.<\/p>\n<figure id=\"attachment_13631\" aria-describedby=\"caption-attachment-13631\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13631 size-large\" src=\"https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/53786359028_7fae1d4f29_o-800x533.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/53786359028_7fae1d4f29_o-800x533.jpg 800w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/53786359028_7fae1d4f29_o-300x200.jpg 300w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/53786359028_7fae1d4f29_o-768x512.jpg 768w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/53786359028_7fae1d4f29_o-1536x1024.jpg 1536w, https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/53786359028_7fae1d4f29_o-2048x1365.jpg 2048w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><figcaption id=\"caption-attachment-13631\" class=\"wp-caption-text\">Cr\u00e9dit : Classical:NEXT, #Cnext24 | Photo : twinematics<\/figcaption><\/figure>\n<p>Restez \u00e0 I&#8217;aff\u00fbt pour le troisi\u00e8me et dernier billet de cette s\u00e9rie, qui portera sur <strong>les nouveaux publics et la mani\u00e8re de les fid\u00e9liser<\/strong> (gros <em>cliffhanger<\/em>!). En attendant, pour avoir un avant-go\u00fbt de l&#8217;exp\u00e9rience C:N en format vid\u00e9o, jetez un coup d&#8217;\u0153il aux <a href=\"https:\/\/www.instagram.com\/stories\/highlights\/17945225678805186\/\">stories Instagram<\/a> que j&#8217;ai puli\u00e9es pendant mon s\u00e9jour \u00e0 Berlin! Je suis profond\u00e9ment reconnaissante du g\u00e9n\u00e9reux financement accord\u00e9 par le Conseil des Arts du Canada dans le cadre du <a href=\"https:\/\/conseildesarts.ca\/financement\/subventions\/appuyer-la-pratique-artistique\/perfectionnement-des-professionnels-des-arts?_gl=1*1pzbkkj*_ga*NTIxMzE3MDEuMTcxNzE3MzA0Ng..*_ga_7GXS0BDFM2*MTcxNzE3MzA0NS4xLjEuMTcxNzE3NTYwMS4wLjAuMA..*_ga_81G873V43T*MTcxNzE3MzA0NS4xLjEuMTcxNzE3NTYwMS42MC4wLjA.\">Perfectionnement des professionnels des arts : Appuyer la pratique artistique<\/a> qui a rendu possible mon voyage en Allemagne pour assister \u00e0 Classical:NEXT.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em>Nous remercions le Conseil des arts du Canada de son soutien.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2851 aligncenter\" src=\"https:\/\/oc.ca\/wp-content\/uploads\/2019\/02\/CCA.jpg\" alt=\"Logo, Canada Council for the Arts logo\" width=\"277\" height=\"51\" srcset=\"https:\/\/oc.ca\/wp-content\/uploads\/2019\/02\/CCA.jpg 500w, https:\/\/oc.ca\/wp-content\/uploads\/2019\/02\/CCA-300x55.jpg 300w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><\/p>\n<p><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:1,&quot;335551620&quot;:1,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Boran Zaza, directrice des communications et du d\u00e9veloppement d&#8217;Orchestres Canada Du 13 au 17 mai 2024, j&#8217;ai assist\u00e9 \u00e0 Classical:NEXT \u00e0 Berlin, en Allemagne. Voici la deuxi\u00e8me partie d&#8217;une s\u00e9rie de trois articles de blog intitul\u00e9s \u00ab Ce que j&#8217;ai appris \u00e0 Classical:NEXT. \u00bb Vous pouvez lire la premi\u00e8re partie ici : Mod\u00e8les de [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[540,231],"tags":[],"class_list":["post-13645","post","type-post","status-publish","format-standard","hentry","category-blogroll-fr","category-blogue"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9veloppement environnemental durable dans les orchestres : Ce que j&#039;ai appris \u00e0 Classical:NEXT - Orchestras Canada\/Orchestres Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9veloppement environnemental durable dans les orchestres : Ce que j&#039;ai appris \u00e0 Classical:NEXT - Orchestras Canada\/Orchestres Canada\" \/>\n<meta property=\"og:description\" content=\"Par Boran Zaza, directrice des communications et du d\u00e9veloppement d&#8217;Orchestres Canada Du 13 au 17 mai 2024, j&#8217;ai assist\u00e9 \u00e0 Classical:NEXT \u00e0 Berlin, en Allemagne. Voici la deuxi\u00e8me partie d&#8217;une s\u00e9rie de trois articles de blog intitul\u00e9s \u00ab Ce que j&#8217;ai appris \u00e0 Classical:NEXT. \u00bb Vous pouvez lire la premi\u00e8re partie ici : Mod\u00e8les de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/\" \/>\n<meta property=\"og:site_name\" content=\"Orchestras Canada\/Orchestres Canada\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-21T21:36:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-22T00:28:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/231212_3Fragenan_Duesseldorfer_Symphoniker-Tonhalle_Foto-Susanne_Diesner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Boran Zaza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Boran Zaza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\\\/\"},\"author\":{\"name\":\"Boran Zaza\",\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#\\\/schema\\\/person\\\/7796a50335e35c17d46b21fce90bda6a\"},\"headline\":\"D\u00e9veloppement environnemental durable dans les orchestres : Ce que j&#8217;ai appris \u00e0 Classical:NEXT\",\"datePublished\":\"2024-06-21T21:36:46+00:00\",\"dateModified\":\"2024-06-22T00:28:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\\\/\"},\"wordCount\":1543,\"publisher\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oc.ca\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/2022_11_01_Boran_Headshots_227OC.png\",\"articleSection\":[\"Blogroll\",\"Blogue\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\\\/\",\"url\":\"https:\\\/\\\/oc.ca\\\/fr\\\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\\\/\",\"name\":\"D\u00e9veloppement environnemental durable dans les orchestres : Ce que j'ai appris \u00e0 Classical:NEXT - Orchestras Canada\\\/Orchestres Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oc.ca\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/2022_11_01_Boran_Headshots_227OC.png\",\"datePublished\":\"2024-06-21T21:36:46+00:00\",\"dateModified\":\"2024-06-22T00:28:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oc.ca\\\/fr\\\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\\\/#primaryimage\",\"url\":\"https:\\\/\\\/oc.ca\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/2022_11_01_Boran_Headshots_227OC.png\",\"contentUrl\":\"https:\\\/\\\/oc.ca\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/2022_11_01_Boran_Headshots_227OC.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oc.ca\\\/fr\\\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/oc.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9veloppement environnemental durable dans les orchestres : Ce que j&#8217;ai appris \u00e0 Classical:NEXT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/oc.ca\\\/en\\\/\",\"name\":\"Orchestras Canada\\\/Orchestres Canada\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oc.ca\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#organization\",\"name\":\"Orchestras Canada\\\/Orchestres Canada\",\"url\":\"https:\\\/\\\/oc.ca\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oc.ca\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/cropped-OC-Logo-800x200-1.png\",\"contentUrl\":\"https:\\\/\\\/oc.ca\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/cropped-OC-Logo-800x200-1.png\",\"width\":400,\"height\":100,\"caption\":\"Orchestras Canada\\\/Orchestres Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/oc.ca\\\/en\\\/#\\\/schema\\\/person\\\/7796a50335e35c17d46b21fce90bda6a\",\"name\":\"Boran Zaza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56b5fa935f2a6deb56743eedfecce8f25a520084588141457887d2c9648c9c08?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56b5fa935f2a6deb56743eedfecce8f25a520084588141457887d2c9648c9c08?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56b5fa935f2a6deb56743eedfecce8f25a520084588141457887d2c9648c9c08?s=96&d=mm&r=g\",\"caption\":\"Boran Zaza\"},\"url\":\"https:\\\/\\\/oc.ca\\\/fr\\\/author\\\/boranzaza\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9veloppement environnemental durable dans les orchestres : Ce que j'ai appris \u00e0 Classical:NEXT - Orchestras Canada\/Orchestres Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9veloppement environnemental durable dans les orchestres : Ce que j'ai appris \u00e0 Classical:NEXT - Orchestras Canada\/Orchestres Canada","og_description":"Par Boran Zaza, directrice des communications et du d\u00e9veloppement d&#8217;Orchestres Canada Du 13 au 17 mai 2024, j&#8217;ai assist\u00e9 \u00e0 Classical:NEXT \u00e0 Berlin, en Allemagne. Voici la deuxi\u00e8me partie d&#8217;une s\u00e9rie de trois articles de blog intitul\u00e9s \u00ab Ce que j&#8217;ai appris \u00e0 Classical:NEXT. \u00bb Vous pouvez lire la premi\u00e8re partie ici : Mod\u00e8les de [&hellip;]","og_url":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/","og_site_name":"Orchestras Canada\/Orchestres Canada","article_published_time":"2024-06-21T21:36:46+00:00","article_modified_time":"2024-06-22T00:28:54+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/oc.ca\/wp-content\/uploads\/2024\/06\/231212_3Fragenan_Duesseldorfer_Symphoniker-Tonhalle_Foto-Susanne_Diesner.jpg","type":"image\/jpeg"}],"author":"Boran Zaza","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Boran Zaza","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/#article","isPartOf":{"@id":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/"},"author":{"name":"Boran Zaza","@id":"https:\/\/oc.ca\/en\/#\/schema\/person\/7796a50335e35c17d46b21fce90bda6a"},"headline":"D\u00e9veloppement environnemental durable dans les orchestres : Ce que j&#8217;ai appris \u00e0 Classical:NEXT","datePublished":"2024-06-21T21:36:46+00:00","dateModified":"2024-06-22T00:28:54+00:00","mainEntityOfPage":{"@id":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/"},"wordCount":1543,"publisher":{"@id":"https:\/\/oc.ca\/en\/#organization"},"image":{"@id":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/#primaryimage"},"thumbnailUrl":"https:\/\/oc.ca\/wp-content\/uploads\/2022\/12\/2022_11_01_Boran_Headshots_227OC.png","articleSection":["Blogroll","Blogue"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/","url":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/","name":"D\u00e9veloppement environnemental durable dans les orchestres : Ce que j'ai appris \u00e0 Classical:NEXT - Orchestras Canada\/Orchestres Canada","isPartOf":{"@id":"https:\/\/oc.ca\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/#primaryimage"},"image":{"@id":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/#primaryimage"},"thumbnailUrl":"https:\/\/oc.ca\/wp-content\/uploads\/2022\/12\/2022_11_01_Boran_Headshots_227OC.png","datePublished":"2024-06-21T21:36:46+00:00","dateModified":"2024-06-22T00:28:54+00:00","breadcrumb":{"@id":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/#primaryimage","url":"https:\/\/oc.ca\/wp-content\/uploads\/2022\/12\/2022_11_01_Boran_Headshots_227OC.png","contentUrl":"https:\/\/oc.ca\/wp-content\/uploads\/2022\/12\/2022_11_01_Boran_Headshots_227OC.png"},{"@type":"BreadcrumbList","@id":"https:\/\/oc.ca\/fr\/developpement-environnemental-durable-dans-les-orchestres-ce-que-jai-appris-a-classicalnext\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oc.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9veloppement environnemental durable dans les orchestres : Ce que j&#8217;ai appris \u00e0 Classical:NEXT"}]},{"@type":"WebSite","@id":"https:\/\/oc.ca\/en\/#website","url":"https:\/\/oc.ca\/en\/","name":"Orchestras Canada\/Orchestres Canada","description":"","publisher":{"@id":"https:\/\/oc.ca\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oc.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/oc.ca\/en\/#organization","name":"Orchestras Canada\/Orchestres Canada","url":"https:\/\/oc.ca\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/oc.ca\/en\/#\/schema\/logo\/image\/","url":"https:\/\/oc.ca\/wp-content\/uploads\/2019\/03\/cropped-OC-Logo-800x200-1.png","contentUrl":"https:\/\/oc.ca\/wp-content\/uploads\/2019\/03\/cropped-OC-Logo-800x200-1.png","width":400,"height":100,"caption":"Orchestras Canada\/Orchestres Canada"},"image":{"@id":"https:\/\/oc.ca\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/oc.ca\/en\/#\/schema\/person\/7796a50335e35c17d46b21fce90bda6a","name":"Boran Zaza","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/56b5fa935f2a6deb56743eedfecce8f25a520084588141457887d2c9648c9c08?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56b5fa935f2a6deb56743eedfecce8f25a520084588141457887d2c9648c9c08?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56b5fa935f2a6deb56743eedfecce8f25a520084588141457887d2c9648c9c08?s=96&d=mm&r=g","caption":"Boran Zaza"},"url":"https:\/\/oc.ca\/fr\/author\/boranzaza\/"}]}},"_links":{"self":[{"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/posts\/13645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/comments?post=13645"}],"version-history":[{"count":10,"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/posts\/13645\/revisions"}],"predecessor-version":[{"id":13665,"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/posts\/13645\/revisions\/13665"}],"wp:attachment":[{"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/media?parent=13645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/categories?post=13645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oc.ca\/fr\/wp-json\/wp\/v2\/tags?post=13645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}